{"id":202,"count":13,"description":"","link":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/","name":"Bags","slug":"bags","taxonomy":"product_cat","parent":198,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bags Archive - JULIANA MARTEJEVS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bags Archive - JULIANA MARTEJEVS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/\" \/>\n<meta property=\"og:site_name\" content=\"JULIANA MARTEJEVS\" \/>\n<meta property=\"og:image\" content=\"https:\/\/julianamartejevs.com\/wp-content\/uploads\/2023\/05\/Website-Header-Mai-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"955\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/product-category\\\/product\\\/bags\\\/\",\"url\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/product-category\\\/product\\\/bags\\\/\",\"name\":\"Bags Archive - JULIANA MARTEJEVS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/product-category\\\/product\\\/bags\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/product-category\\\/product\\\/bags\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product\",\"item\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/product-category\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bags\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/\",\"name\":\"JULIANA MARTEJEVS\",\"description\":\"Moderne Schnittmuster\",\"publisher\":{\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/#organization\",\"name\":\"JULIANA MARTEJEVS\",\"url\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/julianamartejevs.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Logo_The-DIY-Fashion-Label-EN.png\",\"contentUrl\":\"https:\\\/\\\/julianamartejevs.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Logo_The-DIY-Fashion-Label-EN.png\",\"width\":112,\"height\":112,\"caption\":\"JULIANA MARTEJEVS\"},\"image\":{\"@id\":\"https:\\\/\\\/julianamartejevs.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JULIANAMARTEJEVSDE\",\"https:\\\/\\\/www.instagram.com\\\/julianamartejevs_official\\\/?hl=de\",\"https:\\\/\\\/www.pinterest.de\\\/julianamartejevs_official\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCF9HULq8DNy9Yw9LCcXd5ow\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bags Archive - JULIANA MARTEJEVS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/","og_locale":"en_US","og_type":"article","og_title":"Bags Archive - JULIANA MARTEJEVS","og_url":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/","og_site_name":"JULIANA MARTEJEVS","og_image":[{"width":1920,"height":955,"url":"https:\/\/julianamartejevs.com\/wp-content\/uploads\/2023\/05\/Website-Header-Mai-2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/","url":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/","name":"Bags Archive - JULIANA MARTEJEVS","isPartOf":{"@id":"https:\/\/julianamartejevs.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/julianamartejevs.com\/en\/"},{"@type":"ListItem","position":2,"name":"Product","item":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/"},{"@type":"ListItem","position":3,"name":"Bags"}]},{"@type":"WebSite","@id":"https:\/\/julianamartejevs.com\/en\/#website","url":"https:\/\/julianamartejevs.com\/en\/","name":"JULIANA MARTEJEVS","description":"Moderne Schnittmuster","publisher":{"@id":"https:\/\/julianamartejevs.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/julianamartejevs.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/julianamartejevs.com\/en\/#organization","name":"JULIANA MARTEJEVS","url":"https:\/\/julianamartejevs.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/julianamartejevs.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/julianamartejevs.com\/wp-content\/uploads\/2022\/08\/Logo_The-DIY-Fashion-Label-EN.png","contentUrl":"https:\/\/julianamartejevs.com\/wp-content\/uploads\/2022\/08\/Logo_The-DIY-Fashion-Label-EN.png","width":112,"height":112,"caption":"JULIANA MARTEJEVS"},"image":{"@id":"https:\/\/julianamartejevs.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JULIANAMARTEJEVSDE","https:\/\/www.instagram.com\/julianamartejevs_official\/?hl=de","https:\/\/www.pinterest.de\/julianamartejevs_official\/","https:\/\/www.youtube.com\/channel\/UCF9HULq8DNy9Yw9LCcXd5ow"]}]}},"cat_url":"https:\/\/julianamartejevs.com\/en\/product-category\/product\/bags\/","_links":{"self":[{"href":"https:\/\/julianamartejevs.com\/en\/wp-json\/wp\/v2\/product_cat\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julianamartejevs.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/julianamartejevs.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/julianamartejevs.com\/en\/wp-json\/wp\/v2\/product_cat\/198"}],"wp:post_type":[{"href":"https:\/\/julianamartejevs.com\/en\/wp-json\/wp\/v2\/product?product_cat=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}